{"id":2465,"date":"2022-06-02T20:17:39","date_gmt":"2022-06-02T18:17:39","guid":{"rendered":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/?p=2465"},"modified":"2022-06-02T20:17:41","modified_gmt":"2022-06-02T18:17:41","slug":"portes-ouvertes-accueil-des-familles-de-ps","status":"publish","type":"post","link":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/portes-ouvertes-accueil-des-familles-de-ps\/","title":{"rendered":"Portes ouvertes \/ Accueil des familles de PS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vendredi 20 mai, \u00e0 partir de 17h30, l&#8217;\u00e9cole a ouvert ses portes. L&#8217;occasion pour des dizaines de personnes de d\u00e9couvrir les projets v\u00e9cus au sein des classes, de discuter avec les enseignants, d&#8217;aller dans le futur niveau qui sera fr\u00e9quent\u00e9 \u00e0 la rentr\u00e9e prochaine. Une soir\u00e9e tr\u00e8s appr\u00e9ci\u00e9e. Appr\u00e9ci\u00e9s \u00e9galement ce pot offert par l&#8217;APEL et la pr\u00e9sence de grands jeux sur la cour.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2466\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713-1024x768.jpg\" alt=\"\" class=\"wp-image-2466\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3713.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2469\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717-1024x768.jpg\" alt=\"\" class=\"wp-image-2469\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/IMG_3717.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Samedi 21 mai, ce sont les futurs PS qui ont \u00e9t\u00e9 accueillis au sein des classes sur trois horaires diff\u00e9rents. Rencontre avec enseignantes et ASEM, temps d&#8217;information.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2472\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023-1024x768.jpg\" alt=\"\" class=\"wp-image-2472\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091023.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2471\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145-1024x768.jpg\" alt=\"\" class=\"wp-image-2471\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091145.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2470\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206-1024x768.jpg\" alt=\"\" class=\"wp-image-2470\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2022\/06\/20220521_091206.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vendredi 20 mai, \u00e0 partir de 17h30, l&#8217;\u00e9cole a ouvert ses portes. L&#8217;occasion pour des dizaines de personnes de d\u00e9couvrir les projets v\u00e9cus au sein des classes, de discuter avec &#8230;<\/p>\n","protected":false},"author":3,"featured_media":2473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-2465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lecole-en-action"],"_links":{"self":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":1,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"predecessor-version":[{"id":2474,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/2465\/revisions\/2474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/media\/2473"}],"wp:attachment":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}