{"id":8563,"date":"2026-04-14T15:12:23","date_gmt":"2026-04-14T13:12:23","guid":{"rendered":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/?p=8563"},"modified":"2026-04-14T15:12:23","modified_gmt":"2026-04-14T13:12:23","slug":"voyage-au-vietnam-pour-les-ce1b","status":"publish","type":"post","link":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/voyage-au-vietnam-pour-les-ce1b\/","title":{"rendered":"Voyage au Vietnam pour les CE1b."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Louis et sa maman nous ont fait voyager dans leur pays d&#8217;origine : le Vietnam \u00e0 travers quelques photos de leur voyage. Nous avons d\u00e9couvert quelques traditions, cadeaux, mots et la d\u00e9couverte de l&#8217;utilisation des baguettes.<br>Un grand merci !\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918-1024x768.jpg\" alt=\"\" class=\"wp-image-8564\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_141918.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802-1024x768.jpg\" alt=\"\" class=\"wp-image-8565\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802-1024x768.jpg 1024w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802-300x225.jpg 300w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802-768x576.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802-350x263.jpg 350w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_144802.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_143404-768x1024.jpg\" alt=\"\" class=\"wp-image-8566\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_143404-768x1024.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_143404-225x300.jpg 225w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_143404-263x350.jpg 263w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260410_143404-rotated.jpg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260413_181659-768x1024.jpg\" alt=\"\" class=\"wp-image-8567\" srcset=\"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260413_181659-768x1024.jpg 768w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260413_181659-225x300.jpg 225w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260413_181659-263x350.jpg 263w, https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-content\/uploads\/sites\/2\/2026\/04\/20260413_181659-rotated.jpg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Louis et sa maman nous ont fait voyager dans leur pays d&#8217;origine : le Vietnam \u00e0 travers quelques photos de leur voyage. Nous avons d\u00e9couvert quelques traditions, cadeaux, mots et &#8230;<\/p>\n","protected":false},"author":3,"featured_media":8565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,38],"tags":[],"class_list":["post-8563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ce1","category-cycle-2"],"_links":{"self":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/8563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/comments?post=8563"}],"version-history":[{"count":2,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/8563\/revisions"}],"predecessor-version":[{"id":8569,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/posts\/8563\/revisions\/8569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/media\/8565"}],"wp:attachment":[{"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/media?parent=8563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/categories?post=8563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.es-jmm-savenay.fr\/ecole-notre-dame-savenay\/wp-json\/wp\/v2\/tags?post=8563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}